{"id":823,"date":"2018-06-22T17:06:39","date_gmt":"2018-06-22T15:06:39","guid":{"rendered":"http:\/\/new.cashlab.fr\/marc-35-ans-dafjrhfb-partie-2\/"},"modified":"2024-03-28T16:47:12","modified_gmt":"2024-03-28T15:47:12","slug":"bonnes-pratiques-startup-digitalisation-processus","status":"publish","type":"post","link":"https:\/\/www.cashlab.fr\/en\/bonnes-pratiques-startup-digitalisation-processus\/","title":{"rendered":"Start-up best practice"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h5><strong>Les bonnes pratiques en startup, la digitalisation des processus<\/strong><\/h5>\n<p class=\"p1\"><span class=\"s1\">Dans\u00a0<span class=\"s2\">la premi\u00e8re partie de cet article<\/span> nous vous racontions les m\u00e9saventures de Marc, DAF dans une petite structure \u00ab condamn\u00e9 \u00bb \u00e0 digitaliser sa fonction et faire \u00e9voluer ses process. L&rsquo;objectif \u00e9tant de <strong>s\u2019adapter<\/strong> \u00e0 un univers de plus en plus concurrentiel et aux sp\u00e9cificit\u00e9s du monde des startups. Voici un condens\u00e9 de bonnes pratiques pour une bonne digitalisation des processus et vous aider \u00e0 <strong>garder le cap<\/strong>. Notamment lorsqu\u2019il vous faut \u00eatre \u00e0 la fois Directeur Administratif, Financier, Juridique et Ressources Humaines (et parfois m\u00eame responsable des Fournitures de Bureaux).<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p>\n<h3 class=\"p2\" style=\"text-align: left;\"><span class=\"s1\"><b>Qu\u2019entend-t-on exactement par \u00ab\u00a0digitalisation\u00a0\u00bb\u00a0?<\/b><\/span><\/h3>\n<p class=\"p1\"><span class=\"s1\">La digitalisation de l\u2019entreprise consiste en la mise en place de <strong>solutions technologiques sp\u00e9cialis\u00e9es<\/strong> (mais entre lesquelles il existe bien souvent des connexions). Et ont pour objectif de transformer les usages et am\u00e9liorer les performances de l\u2019entreprise. De fait, l\u2019utilisation du bon outil permet, au mieux d\u2019obtenir un r\u00e9sultat plus satisfaisant qu\u2019auparavant (augmenter le degr\u00e9 d\u2019analyse, r\u00e9duire la marge d\u2019erreur des pr\u00e9visions\u2026) et \u00ab au pire \u00bb de gagner un temps pr\u00e9cieux dans la r\u00e9alisation de t\u00e2ches.\u00a0<\/span><\/p>\n<p class=\"p1\"><strong><span class=\"s1\">Voici donc nos bonnes pratiques en terme de digitalisation des processus :<\/span><\/strong><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p>\n<h4 class=\"p3\" style=\"text-align: left;\"><span class=\"s1\"><b>D\u00e9mat\u00e9rialisation des documents<\/b><\/span><\/h4>\n<p class=\"p1\"><span class=\"s1\">Lorsque l\u2019on parle de digitalisation, la premi\u00e8re chose qui vient en t\u00eate est bien souvent le passage du papier au num\u00e9rique et donc de <strong>d\u00e9mat\u00e9rialisation<\/strong>.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Or, on touche ici le c\u0153ur de la comptabilit\u00e9. Bien que cette d\u00e9mat\u00e9rialisation soit plus large que le simple traitement des factures et inclus tout un processus de GED (gestion \u00e9lectronique de documents). Les bonnes pratiques en terme de d\u00e9mat\u00e9rialisation reposent sur la combinaison de trois technologies pour un processus de d\u00e9mat\u00e9rialisation global :<\/span><\/p>\n<ul>\n<li class=\"p1\"><span class=\"s1\">La reconnaissance optique de caract\u00e8re (ROC),<\/span><\/li>\n<li class=\"p1\">La reconnaissance automatique de documents (RAD),<\/li>\n<li class=\"p1\">La lecture automatique de document (LAD).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">Ces technologies fonctionnent de concert et sont souvent regroup\u00e9es au sein d\u2019un m\u00eame outil comme par exemple le module d\u00e9di\u00e9 de la suite Adobe. A vous de mettre en place les <strong>synergies<\/strong> pour permettre par exemple d\u2019alimenter directement votre CRM ou votre logiciel comptable. Aussi, des solutions comme celles de <a href=\"https:\/\/lp.dimosoftware.com\/logiciel-ged-dimo\/\">DIMO Software<\/a> ou <a href=\"https:\/\/www.symtrax.com\/fr\/\">Symtrax<\/a> permettent de num\u00e9riser, traiter, archiver et int\u00e9grer \u00e0 vos <strong>workflows<\/strong> la plupart de vos documents clefs.<\/span> <span class=\"s4\">Et comme l\u2019on parle de workflows on s\u00e9curise aussi une partie des processus de l\u2019entreprise. La digitalisation renforce ainsi le contr\u00f4le interne.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a0<\/span><span class=\"s1\">\u00a0<\/span><\/p>\n<h4 class=\"p3\" style=\"text-align: left;\"><span class=\"s1\"><b>Travail collaboratif et remont\u00e9e d\u2019information<\/b><\/span><\/h4>\n<p class=\"p1\"><span class=\"s1\">Egalement, la remont\u00e9e d\u2019informations est au c\u0153ur de la digitalisation. Le <strong>partage des t\u00e2ches<\/strong> dans un processus d\u2019arr\u00eat\u00e9 de comptes ou de budget permet d\u2019avoir une vision permanente de l\u2019avanc\u00e9 et des retards pris. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Il est crucial, quelle que soit la taille de l\u2019entreprise, de disposer d\u2019un <strong>outil de travail collaboratif<\/strong> adapt\u00e9. Ainsi, centraliser les \u00e9changes de documents dans un outil d\u00e9di\u00e9 permet par exemple de g\u00e9rer \u00ab le <strong>versioning<\/strong> \u00bb. C\u2019est \u00e0 dire de permettre les r\u00e9visions de documents successives par plusieurs collaborateurs sans perte d\u2019informations et avec une piste d\u2019audit. De facto, cela \u00e9vite la multiplication des fichiers en \u00ab v1 \u00bb, \u00ab v2 \u00bb\u2026\u00a0 Aussi, c<\/span><span class=\"s3\">e partage de t\u00e2ches responsabilisent les intervenants d\u2019une cha\u00eene puisqu\u2019\u00e0 une tache est associ\u00e9 un interlocuteur et un planning. <\/span><span class=\"s1\">Parmi les outils les plus utilis\u00e9s figurent <a href=\"https:\/\/app.asana.com\/\">Asana<\/a>, <a href=\"https:\/\/slack.com\/\">Slack<\/a> et <a href=\"https:\/\/trello.com\/\">Trello<\/a>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4 class=\"p3\" style=\"text-align: left;\"><span class=\"s1\"><b>Signature \u00e9lectronique<\/b><\/span><\/h4>\n<p class=\"p1\"><span class=\"s1\">Dans le prolongement de cette d\u00e9mat\u00e9rialisation, les logiciels de signature \u00e9lectronique s\u2019av\u00e8rent rapidement indispensables. Il en existe plusieurs dont\u00a0<a href=\"http:\/\/www.concordnow.com\/\">Concord<\/a> ou <a href=\"https:\/\/www.verisign.com\/\">Verisign<\/a>. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Gr\u00e2ce \u00e0 eux, il est pratique de disposer d\u2019une facture ou d\u2019un contrat num\u00e9rique\/num\u00e9ris\u00e9. Or, sans solution de signature \u00e9lectronique, impossible de ne pas passer par la case impression. Autre vertu de ces outils, ils permettent de r\u00e9duire significativement le temps de traitement de nombreux dossier\/factures n\u00e9cessitant la signature de collaborateurs parfois en d\u00e9placement. R\u00e9duire ce temps r\u00e9duit notamment<strong> le co\u00fbt final<\/strong> de traitement des factures. Et permet \u00e0 chaque partie de se concentrer davantage sur son c\u0153ur de m\u00e9tier plut\u00f4t que sur la gestion administrative.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p>\n<p>La digitalisation des processus n&rsquo;est pas qu&rsquo;administratif mais aussi financier :<\/p>\n<h4 class=\"p3\" style=\"text-align: left;\"><span class=\"s1\"><b>Gestion des notes de frais<\/b><\/span><\/h4>\n<p class=\"p1\"><span class=\"s1\">Dans les structures de taille moyenne, il y a fort \u00e0 parier que le DAF soit le premier recrutement du \u00ab\u00a0futur\u00a0\u00bb p\u00f4le finance. A ce titre, c\u2019est \u00e9galement \u00e0 lui de g\u00e9rer les notes de frais. DAF Mag relayait sur son site le t\u00e9moignage d\u2019<a href=\"http:\/\/www.daf-mag.fr\/Thematique\/couts-achats-1240\/Breves\/Pourquoi-dematerialisation-factures-est-attitude-adopter-2018-327685.htm#4PHzlZhdebibsIgW.97\">Expensya<\/a>, d\u00e9veloppeur d\u2019une solution permettant de g\u00e9rer ses notes de frais directement sur mobile. Gr\u00e2ce \u00e0 l&rsquo;application, vos employ\u00e9s cr\u00e9ent la note de frais dans l\u2019application en prenant en photo le justificatif. Ensuite, l&rsquo;appli vous transf\u00e8re le justificatif automatiquement. De plus, les factures stock\u00e9es dans le <strong>Cloud<\/strong> peuvent \u00eatre organis\u00e9es suivant les diff\u00e9rents services. Cela permet par exemple, de sensibiliser les \u00e9quipes sur les \u00e9conomies r\u00e9alisables et diffuser la <strong>culture cash<\/strong> au sein de l\u2019entreprise.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Aussi, d\u2019autres solutions telles que <a href=\"https:\/\/www.mooncard.co\/\">Mooncard<\/a> proposent de coupler une application semblable \u00e0 celle d\u2019Expensya avec une carte de cr\u00e9dit. Ceci permet de renseigner de mani\u00e8re automatique : <\/span><\/p>\n<ul>\n<li class=\"p1\"><span class=\"s1\">un certain nombre d\u2019informations concernant <\/span><span class=\"s1\">la d\u00e9pense<\/span><span class=\"s4\">, <\/span><\/li>\n<li class=\"p1\"><span class=\"s4\">de plafonner le montant des d\u00e9penses.<\/span><\/li>\n<\/ul>\n<p><span class=\"s1\">Ainsi on <strong>gagne du temps<\/strong> dans le traitement de la d\u00e9pense.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4 class=\"p3\" style=\"text-align: left;\"><span class=\"s1\"><b>Traitement des factures<\/b><\/span><\/h4>\n<p class=\"p1\"><span class=\"s1\">La r\u00e9glementation sur la facture num\u00e9rique s\u2019est grandement assouplie et dans le cas o\u00f9 c\u2019est \u00e0 vous de la num\u00e9riser, il faut d\u00e9sormais \u00eatre en capacit\u00e9 de la traiter en automatique. C\u2019est l\u00e0 qu\u2019interviennent des solutions d\u00e9di\u00e9es comme <a href=\"https:\/\/www.esker.fr\/\">Esker<\/a> ou <a href=\"https:\/\/www.yooz.fr\/\">Yooz<\/a>. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">En effet, elles proposent de digitaliser tout ou une partie des processus Clients \u00ab <strong>Order to Cash<\/strong> \u00bb et Fournisseurs \u00ab <strong>Purchase to Pay<\/strong> \u00bb. Puis elles incluent un workflow de validation lui aussi d\u00e9mat\u00e9rialis\u00e9. Les gains en terme de productivit\u00e9 sont rapidement mesurables. Ils seront d\u2019autant plus appr\u00e9ciables au fur et \u00e0 mesure de la croissance de votre entreprise. Si les <strong>flux de factures<\/strong> sont facilement g\u00e9rables dans les premiers temps, il est indispensable d\u2019anticiper pour en maitriser le volume \u00e0 traiter sur le long terme sans \u00eatre submerg\u00e9 et en y maitrisant le co\u00fbt de traitement.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4 class=\"p2\" style=\"text-align: left;\"><span class=\"s1\"><b>Et la gestion de tr\u00e9sorerie dans tout \u00e7a ?<\/b><\/span><\/h4>\n<p class=\"p1\"><span class=\"s1\">Au del\u00e0 de la partie \u00ab administrative \u00bb, le v\u00e9ritable enjeu de la digitalisation est clair : permettre au DAF de rapprocher plus rapidement donn\u00e9es comptables et donn\u00e9es de gestion. En effet, l&rsquo;objectif final est de pouvoir <strong>prendre des d\u00e9cisions<\/strong> sans perdre de temps \u00e0 traiter les informations qui lui remontent. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Le rapprochement et le traitement des donn\u00e9es sont d\u00e9sormais r\u00e9alis\u00e9s de mani\u00e8re quasi automatique. Des logiciels de <strong>Business Intelligence (BI)\/Data Visualisation<\/strong> sont capables de transformer un flux de donn\u00e9es en graphiques \u00e0 forte valeur ajout\u00e9e. Parfois, ces logiciels transforment les donn\u00e9es directement en rapports personnalisables selon vos attentes. Malheureusement, trop de DAF utilisent encore des tableurs EXCEL pour r\u00e9aliser leur <strong>reporting<\/strong>. C&rsquo;est impensable lorsque l\u2019on sait que <\/span><a href=\"https:\/\/www.linkedin.com\/pulse\/90-des-financiers-seraient-incapables-je-mexplique-laurent-marcellin\/\"><span class=\"s3\">88<\/span><span class=\"s1\">% des feuilles Excel comportent des erreurs\u00a0<\/span><\/a><span class=\"s1\"><a href=\"https:\/\/www.linkedin.com\/pulse\/90-des-financiers-seraient-incapables-je-mexplique-laurent-marcellin\/\">!<\/a> Bien entendu, par souci d\u2019impartialit\u00e9 nous ne vous recommanderons pas d\u2019outil et n\u2019\u00e9voquerons pas non plus <a href=\"https:\/\/www.cashlab.fr\/\"><span class=\"s2\">CashLab. CashLab est l&rsquo;outil combinant pr\u00e9visions de tr\u00e9sorerie \u00e0 long terme et \u00e9l\u00e9ments essentiels de reporting\u2026<\/span><\/a>\u00a0<\/span><\/p>\n<p>Apr\u00e8s lecture de cet article, par quoi allez-vous commencer pour entamer votre digitalisation des processus ?<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Suivez de pr\u00e8s votre tr\u00e9sorerie de mani\u00e8re claire et optimis\u00e9e avec\u00a0<a href=\"https:\/\/www.cashlab.fr\" target=\"_blank\" rel=\"noopener noreferrer\">notre outil Cashlab<\/a>.<\/strong><br \/>\n[\/et_pb_text][et_pb_cta button_url=\u00a0\u00bbhttps:\/\/www.cashlab.fr\/planifier-une-demo\/\u00a0\u00bb button_text=\u00a0\u00bbPlanifier ma d\u00e9mo\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb background_color=\u00a0\u00bb#001F47&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb16px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_font=\u00a0\u00bb||||||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x41;||divi||400&Prime; button_alignment=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_cta][et_pb_cta button_url=\u00a0\u00bbhttps:\/\/www.cashlab.fr\/planifier-une-demo\/ \u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbPlanifier ma d\u00e9mo\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb admin_label=\u00a0\u00bbAppel d&#039;action\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb background_color=\u00a0\u00bb#ffffff\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#5271ff\u00a0\u00bb button_border_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_font=\u00a0\u00bb||||||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x41;||divi||400&Prime; button_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb5px||5px\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb global_module=\u00a0\u00bb2086&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Startup best practices, digitisation of processes: Here is a compendium of good practices in terms of digitisation to help you stay on track. Especially when you need to be an Administrative Director at the same time,<\/p>","protected":false},"author":2,"featured_media":10988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p class=\"p1\"><span class=\"s1\"><i>Dans\u00a0<\/i><a href=\"http:\/\/www.linkedin.com\/\"><span class=\"s2\"><i>la premi\u00e8re partie de cet article<\/i><\/span><\/a><i>\u00a0nous vous racontions les m\u00e9saventures de Marc, DAF dans une petite structure \u00ab\u00a0condamn\u00e9\u00a0\u00bb \u00e0 digitaliser sa fonction et faire \u00e9voluer ses process pour s\u2019adapter \u00e0 un univers de plus en plus concurrentiel et aux sp\u00e9cifit\u00e9 du monde des startups. Voici un condens\u00e9 de bonnes pratiques en terme de digitalisation pour vous aider \u00e0 garder le cap lorsqu\u2019il vous faut \u00eatre \u00e0 la fois Directeur Administratif, Financier, Juridique et Ressources Humaines (et parfois m\u00eame responsable des Fournitures de Bureaux).<\/i><\/span><\/p><p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p><h2 class=\"p2\"><span class=\"s1\"><b>Qu\u2019entend-t-on exactement par \u00ab\u00a0digitalisation\u00a0\u00bb\u00a0?<\/b><\/span><\/h2><p class=\"p1\"><span class=\"s1\">La digitalisation de l\u2019entreprise consiste en la mise en place de solutions technologiques sp\u00e9cialis\u00e9es (mais entre lesquelles il existe bien souvent des connexions) visant \u00e0 transformer les usages et am\u00e9liorer les performances de l\u2019entreprise. De fait, l\u2019utilisation du bon outil permet, au mieux d\u2019obtenir un r\u00e9sultat plus satisfaisant qu\u2019auparavant (augmenter le degr\u00e9 d\u2019analyse, r\u00e9duire la marge d\u2019erreur des pr\u00e9visions\u2026) et \u00ab\u00a0au pire\u00a0\u00bb de gagner un temps pr\u00e9cieux dans la r\u00e9alisation de t\u00e2ches.\u00a0<\/span><\/p><p class=\"p1\"><span class=\"s1\">Voici donc nos bonnes pratiques en terme de digitalisation des processus :<\/span><\/p><p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p><h2 class=\"p3\"><span class=\"s1\"><b>D\u00e9mat\u00e9rialisation des documents<\/b><\/span><\/h2><p class=\"p1\"><span class=\"s1\">Lorsque l\u2019on parle de digitalisation, la premi\u00e8re chose qui vient en t\u00eate est bien souvent le passage du papier au num\u00e9rique et donc de d\u00e9mat\u00e9rialisation.<\/span><\/p><p class=\"p1\"><span class=\"s1\">On touche ici le c\u0153ur de la comptabilit\u00e9. bien que cette d\u00e9mat\u00e9rialisation soit plus large que le simple traitement des factures et inclus tout un processus de GED (gestion \u00e9lectronique de documents). Les bonnes pratiques en terme de d\u00e9mat\u00e9rialisation reposent sur la combinaison de trois technologies pour un processus de d\u00e9mat\u00e9rialisation global\u00a0:<\/span><\/p><p class=\"p1\"><span class=\"s1\">-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La reconnaissance optique de caract\u00e8re (ROC),<\/span><\/p><p class=\"p1\"><span class=\"s1\">-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La reconnaissance automatique de documents\u00a0(RAD),<\/span><\/p><p class=\"p1\"><span class=\"s1\">-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La lecture automatique de document (LAD).<\/span><\/p><p class=\"p1\"><span class=\"s1\">Ces technologies fonctionnent de concert et sont souvent regroup\u00e9es au sein d\u2019un m\u00eame outil comme par exemple le module d\u00e9di\u00e9 de la suite Adobe. A vous de mettre en place les synergies pour permettre par exemple d\u2019alimenter directement votre CRM ou votre logiciel comptable. Des solutions comme celles de <a href=\"https:\/\/www.dimosoftware.fr\/nos-solutions\/gestion-electronique-des-documents-ged\/\">DIMO Software<\/a> ou <a href=\"https:\/\/www.symtrax.com\/fr\/\">Symtrax<\/a> permettent de num\u00e9riser, traiter, archiver et int\u00e9grer \u00e0 vos workflow la plupart de vos documents clefs.<\/span> <span class=\"s4\">Et comme l\u2019on parle de workflow on s\u00e9curise aussi une partie des processus de l\u2019entreprise. La digitalisation renforce ainsi le contr\u00f4le interne.<\/span><\/p><p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p><h2 class=\"p3\"><span class=\"s1\"><b>Traitement des factures<\/b><\/span><\/h2><p class=\"p1\"><span class=\"s1\">La r\u00e9glementation sur la facture num\u00e9rique s\u2019est grandement assouplie et dans le cas o\u00f9 c\u2019est \u00e0 vous de la num\u00e9riser, il faut d\u00e9sormais \u00eatre en capacit\u00e9 de la traiter en automatique. C\u2019est l\u00e0 qu\u2019interviennent des solutions d\u00e9di\u00e9es comme <a href=\"https:\/\/www.esker.fr\/\">Esker<\/a> ou <a href=\"https:\/\/www.yooz.fr\/\">Yooz<\/a> qui proposent de digitaliser tout ou partie des processus Clients \u00ab\u00a0Order to Cash\u00a0\u00bb et Fournisseurs \u00ab\u00a0Purchase to Pay\u00a0\u00bb en y incluant un workflow de validation lui aussi d\u00e9mat\u00e9rialis\u00e9. Les gains en terme de productivit\u00e9 sont rapidement mesurables et seront d\u2019autant plus appr\u00e9ciables au fur et \u00e0 mesure de la croissance de votre entreprise. Si les flux de factures sont facilement g\u00e9rables dans les premiers temps, il est indispensable d\u2019anticiper pour en maitriser le volume \u00e0 traiter sur le long terme sans \u00eatre submerg\u00e9 et en y maitrisant le co\u00fbt de traitement.<\/span><\/p><p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p><h2 class=\"p3\"><span class=\"s1\"><b>Signature \u00e9lectronique<\/b><\/span><\/h2><p class=\"p1\"><span class=\"s1\">Dans le prolongement de cette d\u00e9mat\u00e9rialisation, les logiciels de signature \u00e9lectronique (comme par exemple les services propos\u00e9s par <a href=\"http:\/\/www.concordnow.com\/\">Concord<\/a> ou <a href=\"http:\/\/www.verisign.com\/\">Verisign<\/a>) s\u2019av\u00e8rent rapidement indispensables pour rester dans une logique de d\u00e9mat\u00e9rialisation. En effet il est pratique de disposer d\u2019une facture ou d\u2019un contrat num\u00e9rique\/num\u00e9ris\u00e9, mais sans solution de signature \u00e9lectronique, impossible de ne pas passer par la case impression. Autre vertu de ces outils, ils permettent de r\u00e9duire significativement le temps de traitement de nombreux dossier\/factures n\u00e9cessitant la signature de collaborateurs parfois en d\u00e9placement. R\u00e9duire ce temps r\u00e9duit notamment le co\u00fbt final de traitement des factures et permet \u00e0 chaque partie de se concentrer davantage sur son c\u0153ur de m\u00e9tier plut\u00f4t que sur la gestion administrative.<\/span><\/p><p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p><h2 class=\"p3\"><span class=\"s1\"><b>Gestion des notes de frais<\/b><\/span><\/h2><p class=\"p1\"><span class=\"s1\">Dans les structures de taille moyenne, il y a fort \u00e0 parier que le DAF soit le premier recrutement du \u00ab\u00a0futur\u00a0\u00bb p\u00f4le finance. A ce titre, c\u2019est \u00e9galement \u00e0 lui de g\u00e9rer les notes de frais. DAF Mag relayait sur son site le t\u00e9moignage d\u2019<a href=\"http:\/\/www.daf-mag.fr\/Thematique\/couts-achats-1240\/Breves\/Pourquoi-dematerialisation-factures-est-attitude-adopter-2018-327685.htm#4PHzlZhdebibsIgW.97\">Expensya<\/a>, d\u00e9veloppeur d\u2019une solution permettant de g\u00e9rer ses notes de frais directement sur mobile. Vos employ\u00e9s cr\u00e9ent la note de frais dans l\u2019application et prennent en photo le justificatif qui vous est automatiquement transf\u00e9r\u00e9 pour validation. Les factures stock\u00e9es dans le Cloud peuvent \u00eatre organis\u00e9es suivant les diff\u00e9rents services afin, par exemple, de sensibiliser les \u00e9quipes sur les \u00e9conomies r\u00e9alisables et diffuser la culture cash au sein de l\u2019entreprise.<\/span><\/p><p class=\"p1\"><span class=\"s1\">D\u2019autres solutions telles que <a href=\"https:\/\/www.mooncard.co\/\">Mooncard<\/a> proposent de coupler une application semblable \u00e0 celle d\u2019Expensya avec une carte de cr\u00e9dit. Ceci permet de renseigner de mani\u00e8re automatique un certain nombre d\u2019informations concernant la d\u00e9pense<\/span><span class=\"s4\">, de plafonner le montant des d\u00e9penses<\/span> <span class=\"s1\">et donc de gagner toujours plus de temps dans son traitement.<\/span><\/p><p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p><h2 class=\"p3\"><span class=\"s1\"><b>Travail collaboratif et remont\u00e9e d\u2019information<\/b><\/span><\/h2><p class=\"p1\"><span class=\"s1\">La remont\u00e9e d\u2019informations est elle aussi au c\u0153ur du sujet. Le partage des t\u00e2ches dans un processus d\u2019arr\u00eat\u00e9 de comptes ou de budget permet d\u2019avoir une vision permanente de l\u2019avanc\u00e9 et des retards pris. Il est crucial, quelle que soit la taille de l\u2019entreprise, de disposer d\u2019un outil de travail collaboratif adapt\u00e9. Centraliser les \u00e9changes de documents dans un outil d\u00e9di\u00e9 permet par exemple de g\u00e9rer \u00ab\u00a0le versioning\u00a0\u00bb, c\u2019est \u00e0 dire de permettre les r\u00e9visions de documents successives par plusieurs collaborateurs sans perte d\u2019informations et avec une piste d\u2019audit, le tout en \u00e9vitant la multiplication des fichiers en \u00ab\u00a0v1\u00a0\u00bb, \u00ab\u00a0v2\u00a0\u00bb\u2026 \u00a0<\/span><span class=\"s3\">Ce partage de t\u00e2ches responsabilisent les intervenants d\u2019une chaine puisqu\u2019\u00e0 une tache est associ\u00e9 un interlocuteur et un planning. <\/span><span class=\"s1\">Parmi les outils les plus utilis\u00e9s figurent <a href=\"https:\/\/app.asana.com\/\">Asana<\/a>, <a href=\"https:\/\/slack.com\/\">Slack<\/a> et <a href=\"https:\/\/trello.com\/\">Trello.<\/a><\/span><\/p><p class=\"p1\"><span class=\"s1\">\u00a0<\/span><\/p><h2 class=\"p2\"><span class=\"s1\"><b>Et la gestion de tr\u00e9sorerie dans tout \u00e7a ?<\/b><\/span><\/h2><p class=\"p1\"><span class=\"s1\">Au del\u00e0 de la partie \u00ab\u00a0administrative\u00a0\u00bb, le v\u00e9ritable enjeu de la digitalisation est clair\u00a0: permettre au DAF de rapprocher plus rapidement donn\u00e9es comptables et donn\u00e9es de gestion pour \u00eatre \u00e0 m\u00eame de prendre des d\u00e9cisions sans perdre de temps \u00e0 traiter les informations qui lui remontent. Le rapprochement et le traitement des donn\u00e9es sont d\u00e9sormais r\u00e9alis\u00e9s de mani\u00e8re quasi automatique par des logiciels de Business Intelligence (BI)\/ Data Visualisation capables de transformer un flux de donn\u00e9es en graphiques \u00e0 forte valeur ajout\u00e9e, voir directement en rapports personnalisables selon vos attentes. Trop de DAF utilisent encore des tableurs EXCEL pour r\u00e9aliser leur reporting, impensable lorsque l\u2019on sait que <\/span><a href=\"https:\/\/www.linkedin.com\/pulse\/90-des-financiers-seraient-incapables-je-mexplique-laurent-marcellin\/\"><span class=\"s3\">88<\/span><span class=\"s1\">% des feuilles Excel comportent des erreurs\u00a0<\/span><\/a><span class=\"s1\"><a href=\"https:\/\/www.linkedin.com\/pulse\/90-des-financiers-seraient-incapables-je-mexplique-laurent-marcellin\/\">!<\/a> Bien entendu, par soucis d\u2019impartialit\u00e9 nous ne vous recommanderons pas d\u2019outil ici et n\u2019\u00e9voquerons pas non plus\u00a0<a href=\"http:\/\/www.cashview.fr\/\"><span class=\"s2\">CashView, notre propre outil combinant pr\u00e9visions de tr\u00e9sorerie \u00e0 long terme et \u00e9l\u00e9ments essentiels de reporting\u2026<\/span><\/a>\u00a0Je me contenterai de vous inviter \u00e0 jeter un \u0153il aux autres pages de ce site.<\/span><\/p>","_et_gb_content_width":"","content-type":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[19,7,66,62],"class_list":["post-823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseils","tag-cash","tag-daf","tag-innovation","tag-technologie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les bonnes pratiques en Startup: digitalisation des processus - Cashlab<\/title>\n<meta name=\"description\" content=\"Digitalisation des processus : voici un condens\u00e9 de bonnes pratiques pour vous aider \u00e0 garder le cap lorsqu\u2019il vous devez \u00eatre DAF, RH..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cashlab.fr\/en\/bonnes-pratiques-startup-digitalisation-processus\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les bonnes pratiques en Startup: digitalisation des processus - Cashlab\" \/>\n<meta property=\"og:description\" content=\"Digitalisation des processus : voici un condens\u00e9 de bonnes pratiques pour vous aider \u00e0 garder le cap lorsqu\u2019il vous devez \u00eatre DAF, RH..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cashlab.fr\/en\/bonnes-pratiques-startup-digitalisation-processus\/\" \/>\n<meta property=\"og:site_name\" content=\"Cashlab\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-22T15:06:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-28T15:47:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cashlab.fr\/wp-content\/uploads\/2018\/06\/Les-bonnes-pratiques-en-startup-2-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cashlab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CashLab_fr\" \/>\n<meta name=\"twitter:site\" content=\"@CashLab_fr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cashlab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/\"},\"author\":{\"name\":\"Cashlab\",\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/#\\\/schema\\\/person\\\/bce16b1617294d780056e3e8dfb984f7\"},\"headline\":\"Les bonnes pratiques en Startup\",\"datePublished\":\"2018-06-22T15:06:39+00:00\",\"dateModified\":\"2024-03-28T15:47:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/\"},\"wordCount\":1517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cashlab.fr\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Les-bonnes-pratiques-en-startup-2-2.jpg\",\"keywords\":[\"Cash\",\"DAF\",\"Innovation\",\"Technologie\"],\"articleSection\":[\"Conseils\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/\",\"url\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/\",\"name\":\"Les bonnes pratiques en Startup: digitalisation des processus - Cashlab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cashlab.fr\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Les-bonnes-pratiques-en-startup-2-2.jpg\",\"datePublished\":\"2018-06-22T15:06:39+00:00\",\"dateModified\":\"2024-03-28T15:47:12+00:00\",\"description\":\"Digitalisation des processus : voici un condens\u00e9 de bonnes pratiques pour vous aider \u00e0 garder le cap lorsqu\u2019il vous devez \u00eatre DAF, RH..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cashlab.fr\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Les-bonnes-pratiques-en-startup-2-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cashlab.fr\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Les-bonnes-pratiques-en-startup-2-2.jpg\",\"width\":1080,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/bonnes-pratiques-startup-digitalisation-processus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cashlab.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils\",\"item\":\"https:\\\/\\\/www.cashlab.fr\\\/en\\\/conseils\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les bonnes pratiques en Startup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cashlab.fr\\\/\",\"name\":\"Cashlab\",\"description\":\"Logiciel de pr\u00e9vision et pilotage de tr\u00e9sorerie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cashlab.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/#organization\",\"name\":\"Cashlab\",\"url\":\"https:\\\/\\\/www.cashlab.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cashlab.fr\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo_Cashlab-noir.png\",\"contentUrl\":\"https:\\\/\\\/www.cashlab.fr\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo_Cashlab-noir.png\",\"width\":1583,\"height\":295,\"caption\":\"Cashlab\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/CashLab_fr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cashlab\\\/posts\\\/?feedView=all\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cashlab.fr\\\/#\\\/schema\\\/person\\\/bce16b1617294d780056e3e8dfb984f7\",\"name\":\"Cashlab\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d4f8ceba9ebec1eca2d4376bc9376d0a500efe0add7f124ba4d3bea80be1179?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d4f8ceba9ebec1eca2d4376bc9376d0a500efe0add7f124ba4d3bea80be1179?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d4f8ceba9ebec1eca2d4376bc9376d0a500efe0add7f124ba4d3bea80be1179?s=96&d=mm&r=g\",\"caption\":\"Cashlab\"},\"url\":\"https:\\\/\\\/www.cashlab.fr\\\/en\\\/author\\\/admin-cashlab\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les bonnes pratiques en Startup: digitalisation des processus - Cashlab","description":"Digitalisation des processus : voici un condens\u00e9 de bonnes pratiques pour vous aider \u00e0 garder le cap lorsqu\u2019il vous devez \u00eatre DAF, RH..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cashlab.fr\/en\/bonnes-pratiques-startup-digitalisation-processus\/","og_locale":"en_GB","og_type":"article","og_title":"Les bonnes pratiques en Startup: digitalisation des processus - Cashlab","og_description":"Digitalisation des processus : voici un condens\u00e9 de bonnes pratiques pour vous aider \u00e0 garder le cap lorsqu\u2019il vous devez \u00eatre DAF, RH..","og_url":"https:\/\/www.cashlab.fr\/en\/bonnes-pratiques-startup-digitalisation-processus\/","og_site_name":"Cashlab","article_published_time":"2018-06-22T15:06:39+00:00","article_modified_time":"2024-03-28T15:47:12+00:00","og_image":[{"width":1080,"height":675,"url":"https:\/\/www.cashlab.fr\/wp-content\/uploads\/2018\/06\/Les-bonnes-pratiques-en-startup-2-2.jpg","type":"image\/jpeg"}],"author":"Cashlab","twitter_card":"summary_large_image","twitter_creator":"@CashLab_fr","twitter_site":"@CashLab_fr","twitter_misc":{"Written by":"Cashlab","Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/#article","isPartOf":{"@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/"},"author":{"name":"Cashlab","@id":"https:\/\/www.cashlab.fr\/#\/schema\/person\/bce16b1617294d780056e3e8dfb984f7"},"headline":"Les bonnes pratiques en Startup","datePublished":"2018-06-22T15:06:39+00:00","dateModified":"2024-03-28T15:47:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/"},"wordCount":1517,"commentCount":0,"publisher":{"@id":"https:\/\/www.cashlab.fr\/#organization"},"image":{"@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cashlab.fr\/wp-content\/uploads\/2018\/06\/Les-bonnes-pratiques-en-startup-2-2.jpg","keywords":["Cash","DAF","Innovation","Technologie"],"articleSection":["Conseils"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/","url":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/","name":"Les bonnes pratiques en Startup: digitalisation des processus - Cashlab","isPartOf":{"@id":"https:\/\/www.cashlab.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/#primaryimage"},"image":{"@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cashlab.fr\/wp-content\/uploads\/2018\/06\/Les-bonnes-pratiques-en-startup-2-2.jpg","datePublished":"2018-06-22T15:06:39+00:00","dateModified":"2024-03-28T15:47:12+00:00","description":"Digitalisation des processus : voici un condens\u00e9 de bonnes pratiques pour vous aider \u00e0 garder le cap lorsqu\u2019il vous devez \u00eatre DAF, RH..","breadcrumb":{"@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/#primaryimage","url":"https:\/\/www.cashlab.fr\/wp-content\/uploads\/2018\/06\/Les-bonnes-pratiques-en-startup-2-2.jpg","contentUrl":"https:\/\/www.cashlab.fr\/wp-content\/uploads\/2018\/06\/Les-bonnes-pratiques-en-startup-2-2.jpg","width":1080,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.cashlab.fr\/bonnes-pratiques-startup-digitalisation-processus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cashlab.fr\/"},{"@type":"ListItem","position":2,"name":"Conseils","item":"https:\/\/www.cashlab.fr\/en\/conseils\/"},{"@type":"ListItem","position":3,"name":"Les bonnes pratiques en Startup"}]},{"@type":"WebSite","@id":"https:\/\/www.cashlab.fr\/#website","url":"https:\/\/www.cashlab.fr\/","name":"Cashlab","description":"Logiciel de pr\u00e9vision et pilotage de tr\u00e9sorerie","publisher":{"@id":"https:\/\/www.cashlab.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cashlab.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.cashlab.fr\/#organization","name":"Cashlab","url":"https:\/\/www.cashlab.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.cashlab.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.cashlab.fr\/wp-content\/uploads\/2019\/12\/Logo_Cashlab-noir.png","contentUrl":"https:\/\/www.cashlab.fr\/wp-content\/uploads\/2019\/12\/Logo_Cashlab-noir.png","width":1583,"height":295,"caption":"Cashlab"},"image":{"@id":"https:\/\/www.cashlab.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/CashLab_fr","https:\/\/www.linkedin.com\/company\/cashlab\/posts\/?feedView=all"]},{"@type":"Person","@id":"https:\/\/www.cashlab.fr\/#\/schema\/person\/bce16b1617294d780056e3e8dfb984f7","name":"Cashlab","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/6d4f8ceba9ebec1eca2d4376bc9376d0a500efe0add7f124ba4d3bea80be1179?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d4f8ceba9ebec1eca2d4376bc9376d0a500efe0add7f124ba4d3bea80be1179?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d4f8ceba9ebec1eca2d4376bc9376d0a500efe0add7f124ba4d3bea80be1179?s=96&d=mm&r=g","caption":"Cashlab"},"url":"https:\/\/www.cashlab.fr\/en\/author\/admin-cashlab\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/posts\/823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/comments?post=823"}],"version-history":[{"count":3,"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/posts\/823\/revisions"}],"predecessor-version":[{"id":10992,"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/posts\/823\/revisions\/10992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/media\/10988"}],"wp:attachment":[{"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/media?parent=823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/categories?post=823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cashlab.fr\/en\/wp-json\/wp\/v2\/tags?post=823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}